{"id":7504,"date":"2023-09-07T14:19:28","date_gmt":"2023-09-07T12:19:28","guid":{"rendered":"https:\/\/www.timevision.it\/bonus-lavoro\/?page_id=7504"},"modified":"2024-01-09T09:41:38","modified_gmt":"2024-01-09T08:41:38","slug":"bonus-neet","status":"publish","type":"page","link":"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/","title":{"rendered":"Bonus Neet"},"content":{"rendered":"<h1 class=\"h1-nascosto\">Bonus Neet - Dettagli e approfondimenti<\/h1>\n\n  <div class=\"banner has-hover\" id=\"banner-1627685985\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img fetchpriority=\"high\" decoding=\"async\" width=\"1020\" height=\"453\" src=\"https:\/\/www.timevision.it\/bonus-lavoro\/wp-content\/uploads\/2021\/02\/Persone-svantaggiate-delle-cooperative-sociali-1024x455.png\" class=\"bg attachment-large size-large\" alt=\"Persone svantaggiate delle cooperative sociali\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-393135301\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n\n\t<div id=\"text-3655669414\" class=\"text\">\n\t\t\n\n<h3 style=\"text-align: center;\"><span style=\"font-size: 160%;\">Bonus Neet<\/span><\/h3>\n<p style=\"text-align: center;\"><span class=\"gdlr-core-title-item-caption gdlr-core-info-font gdlr-core-skin-caption\">OCCUPAZIONE<\/span><\/p>\n\t\t\n<style>\n#text-3655669414 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-393135301 {\n  width: 100%;\n}\n#text-box-393135301 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1627685985 {\n  padding-top: 500px;\n}\n#banner-1627685985 .overlay {\n  background-color: rgba(4, 75, 114, 0.866);\n}\n#banner-1627685985 .banner-bg img {\n  object-position: 42% 24%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-1860588700\">\n\n\n\t<div id=\"col-435205366\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-4137600772\" class=\"text\">\n\t\t\n\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<p><span style=\"font-size: 130%; color: #044b72;\">L\u2019incentivo per l\u2019<strong>assunzione Neet<\/strong>&nbsp;\u00e8 stato predisposto dal Decreto Lavoro del 1 maggior 2023 per favorire l\u2019occupazione dei giovani che&nbsp;<strong>non studiano, non si formano e non lavorano<\/strong>, iscritti al Programma Garanzia Giovani.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Quali incentivi sono previsti l&#8217;assunzione dei Neet?<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<p><span style=\"font-size: 130%; color: #044b72;\">I datori di lavoro che dal 1\u00b0 giugno al 31 dicembre di quest\u2019anno assumeranno a tempo indeterminato un giovane sotto i 30 anni disoccupato e non inserito in un percorso di studio o di formazione (\u00abNeet\u00bb), potranno fruire per un anno del bonus previsto dal decreto Lavoro,<strong>&nbsp;pari al 60% della retribuzione, e cumulare questo incentivo con altre agevolazioni.<\/strong><\/span><\/p>\n<p><span style=\"font-size: 130%; color: #044b72;\">Sono due gli incentivi con cui il bonus Neet \u00e8 cumulabile:<\/span><\/p>\n<ul>\n<li><span style=\"font-size: 130%; color: #044b72;\">gli incentivi per l\u2019assunzione di under 36<\/span><\/li>\n<li><span style=\"font-size: 130%; color: #044b72;\">l\u2019apprendistato professionalizzante<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-4137600772 {\n  color: #044b72;\n}\n#text-4137600772 > * {\n  color: #044b72;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-87975103\" class=\"text\">\n\t\t\n\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Chi sono i destinatari di tale agevolazione?<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<p><span style=\"font-size: 130%; color: #044b72;\">I lavoratori che portano in dote il bonus assunzioni Neet devono avere questi tre requisiti:<\/span><\/p>\n<ul>\n<li><span style=\"font-size: 130%; color: #044b72;\">non aver compiuto&nbsp;<strong>30 anni<\/strong>&nbsp;alla data dell\u2019assunzione;<\/span><\/li>\n<li><span style=\"font-size: 130%; color: #044b72;\">non essere occupati n\u00e9 inseriti in corsi di studio o di formazione;<\/span><\/li>\n<li><span style=\"font-size: 130%; color: #044b72;\">essere iscritti al Pon \u00abIniziativa Occupazione Giovani\u00bb.&nbsp;<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 130%; color: #044b72;\">Anche le aziende devono rispettare alcuni requisiti per poter accedere, in generale, agli incentivi e, nello specifico, a questo bonus.<\/span><\/p>\n<p><span style=\"font-size: 130%; color: #044b72;\">L\u2019assunzione deve determinare un incremento occupazionale netto per i 12 mesi successivi, e ci deve essere la piena regolarit\u00e0 contributiva e contrattuale. In caso di licenziamento, il bonus Neet decade.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-87975103 {\n  color: #044b72;\n}\n#text-87975103 > * {\n  color: #044b72;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3191048752\" class=\"text\">\n\t\t\n\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Scheda Tecnica: Bonus Neet<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 130%; color: #044b72;\">A chi si rivolge<\/span><\/td>\n<td>\n<div><span style=\"font-size: 130%; color: #044b72;\">Tutte le aziende<\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 130%; color: #044b72;\">Validit\u00e0<\/span><\/td>\n<td><span style=\"font-size: 130%; color: #044b72;\">12 mesi dalla data di assunzione.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 130%; color: #044b72;\">Target<\/span><\/td>\n<td><span style=\"font-size: 130%; color: #044b72;\">Giovani dai 16 ai 29 anni<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 130%; color: #044b72;\">Incentivo<\/span><\/td>\n<td><span style=\"font-size: 130%; color: #044b72;\">Incentivo economico<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 130%; color: #044b72;\">Contratto<\/span><\/td>\n<td><span style=\"font-size: 130%; color: #044b72;\">Tempo indeterminato<\/span><br><span style=\"font-size: 130%; color: #044b72;\">Apprendistato professionalizzante<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-3191048752 {\n  color: #044b72;\n}\n#text-3191048752 > * {\n  color: #044b72;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3836296256\" class=\"text\">\n\t\t\n\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\"><span class=\"gdlr-core-title-item-caption gdlr-core-info-font gdlr-core-skin-caption\" style=\"font-size: 130%; color: #044b72;\">FAQ<\/span>\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Domande frequenti: Bonus Neet<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Che tipo di incentivo \u00e8 previsto per le assunzioni di Neet?<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<p><span style=\"font-size: 130%; color: #044b72;\">L\u2019incentivo per l\u2019assunzione di Neet \u00e8 un incentivo di natura economica.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Quali sono i dettagli dell&#8217;incentivo assunzione Neet?<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<p><span style=\"font-size: 130%; color: #044b72;\">L\u2019incentivo disponibile \u00e8 pari al 60% della retribuzione mensile prevista per ogni assunzione, per la durata massima di 12 mesi.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-title-item gdlr-core-item-pdb clearfix  gdlr-core-left-align gdlr-core-title-item-caption-top gdlr-core-item-pdlr\">\n<div class=\"gdlr-core-title-item-title-wrap \">\n<h3 class=\"gdlr-core-title-item-title gdlr-core-skin-title \"><span style=\"font-size: 130%; color: #044b72;\">Per quanto tempo sar\u00e0 valido l&#8217;incentivo assunzione Neet?<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\">\n<div class=\"gdlr-core-text-box-item-content\">\n<p><span style=\"font-size: 130%; color: #044b72;\">Le assunzioni devono essere effettuate nel periodo compreso tra il 01\/06\/2023 e il 31\/12\/2023. L\u2019incentivo deve essere fruito, a pena di decadenza, entro il 28\/02\/2025.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gdlr-core-pbf-element\">\n<div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\"><span style=\"font-size: 130%; color: #044b72;\">&nbsp;<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-3836296256 {\n  color: #044b72;\n}\n#text-3836296256 > * {\n  color: #044b72;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle\"  id=\"row-1799685382\">\n\n\n\t<div id=\"col-878463876\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-4055672\" class=\"text\">\n\t\t\n\n<h3><span style=\"font-size: 140%;\">Scarica la guida<\/span><\/h3>\n<p>Scarica il&nbsp;<strong>BOOK TIME VISION<\/strong>&nbsp;dedicato agli Incentivi all\u2019occupazione.&nbsp;<br>Compila ora il form per riceverlo&nbsp;<strong>gratuitamente&nbsp;<\/strong><\/p>\n\t\t\n<style>\n#text-4055672 {\n  color: #044b72;\n}\n#text-4055672 > * {\n  color: #044b72;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1989585846\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js-eu1.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"eu1\",\n    portalId: \"26479973\",\n    formId: \"6dbb6cde-88ce-4433-8892-8daeaeffd189\"\n  });\n<\/script>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bonus Neet &#8211; Dettagli e approfondimenti<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-left-sidebar.php","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-7504","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bonus Neet<\/title>\n<meta name=\"description\" content=\"Operativo da giugno 2023 il bonus Neet | L&#039;incentivo \u00e8 di natura economica e sar\u00e0 valido fino al 2025 | Guida agli incentivi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonus Neet - Bonus Lavoro &amp; incentivi all\u2019assunzione\" \/>\n<meta property=\"og:description\" content=\"Operativo da giugno 2023 il bonus Neet | L&#039;incentivo \u00e8 di natura economica e sar\u00e0 valido fino al 2025 | Guida agli incentivi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonus Lavoro &amp; incentivi all\u2019assunzione\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/timevision\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-09T08:41:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@time_vision\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/\",\"url\":\"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/\",\"name\":\"Bonus Neet - Bonus Lavoro &amp; incentivi all\u2019assunzione\",\"isPartOf\":{\"@id\":\"https:\/\/www.timevision.it\/bonus-lavoro\/#website\"},\"datePublished\":\"2023-09-07T12:19:28+00:00\",\"dateModified\":\"2024-01-09T08:41:38+00:00\",\"description\":\"Operativo da giugno 2023 il bonus Neet | L'incentivo \u00e8 di natura economica e sar\u00e0 valido fino al 2025 | Guida agli incentivi\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.timevision.it\/bonus-lavoro\/#website\",\"url\":\"https:\/\/www.timevision.it\/bonus-lavoro\/\",\"name\":\"Bonus Lavoro &amp; incentivi all\u2019assunzione\",\"description\":\"Guida completa per imprese e commercialisti, tutto su sgravi fiscali e bonus assunzioni 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.timevision.it\/bonus-lavoro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonus Neet","description":"Operativo da giugno 2023 il bonus Neet | L'incentivo \u00e8 di natura economica e sar\u00e0 valido fino al 2025 | Guida agli incentivi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/","og_locale":"it_IT","og_type":"article","og_title":"Bonus Neet - Bonus Lavoro &amp; incentivi all\u2019assunzione","og_description":"Operativo da giugno 2023 il bonus Neet | L'incentivo \u00e8 di natura economica e sar\u00e0 valido fino al 2025 | Guida agli incentivi","og_url":"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/","og_site_name":"Bonus Lavoro &amp; incentivi all\u2019assunzione","article_publisher":"https:\/\/www.facebook.com\/timevision","article_modified_time":"2024-01-09T08:41:38+00:00","twitter_card":"summary_large_image","twitter_site":"@time_vision","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/","url":"https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/","name":"Bonus Neet - Bonus Lavoro &amp; incentivi all\u2019assunzione","isPartOf":{"@id":"https:\/\/www.timevision.it\/bonus-lavoro\/#website"},"datePublished":"2023-09-07T12:19:28+00:00","dateModified":"2024-01-09T08:41:38+00:00","description":"Operativo da giugno 2023 il bonus Neet | L'incentivo \u00e8 di natura economica e sar\u00e0 valido fino al 2025 | Guida agli incentivi","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.timevision.it\/bonus-lavoro\/bonus-neet\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.timevision.it\/bonus-lavoro\/#website","url":"https:\/\/www.timevision.it\/bonus-lavoro\/","name":"Bonus Lavoro &amp; incentivi all\u2019assunzione","description":"Guida completa per imprese e commercialisti, tutto su sgravi fiscali e bonus assunzioni 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.timevision.it\/bonus-lavoro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/pages\/7504"}],"collection":[{"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/comments?post=7504"}],"version-history":[{"count":4,"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/pages\/7504\/revisions"}],"predecessor-version":[{"id":7830,"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/pages\/7504\/revisions\/7830"}],"wp:attachment":[{"href":"https:\/\/www.timevision.it\/bonus-lavoro\/wp-json\/wp\/v2\/media?parent=7504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}