{"id":48153,"date":"2025-03-20T09:26:00","date_gmt":"2025-03-20T08:26:00","guid":{"rendered":"https:\/\/www.timevision.it\/news\/?p=48153"},"modified":"2025-03-19T12:03:39","modified_gmt":"2025-03-19T11:03:39","slug":"bando-viva-opportunita-per-sviluppare-competenze-digitali","status":"publish","type":"post","link":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/","title":{"rendered":"Bando &#8220;vIvA&#8221;: opportunit\u00e0 per sviluppare competenze digitali"},"content":{"rendered":"\n<p>Il <strong>Fondo per la Repubblica Digitale \u2013 Impresa Sociale<\/strong> ha lanciato il bando <strong>\u201cvIvA\u201d<\/strong>, volto a promuovere lo sviluppo di competenze digitali nell&#8217;ambito dell\u2019<strong><a href=\"https:\/\/www.timevision.it\/news\/aziende\/ia-lavoro-un-binomio-analizzato-dal-world-economic-forum\/\">Intelligenza Artificiale<\/a> (IA)<\/strong> a beneficio di <strong>persone in condizioni di vulnerabilit\u00e0<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bando &#8220;vIvA&#8221;: i destinatari<\/h2>\n\n\n\n<p>Il bando &#8220;vIvA&#8221; \u00e8 destinato ad enti pubblici, privati senza scopo di lucro ed enti del terzo settore che vogliono acquisire quelle conoscenze digitali imprescindibili per inclusione sociale e sviluppo economico.  In questo scenario, l\u2019<strong>Intelligenza Artificiale<\/strong> emerge come una delle forze pi\u00f9 trasformative, con un potenziale significativo per rimodellare il panorama economico italiano e assistere una vasta percentuale di lavori.<\/p>\n\n\n\n<p>Il bando \u201cvIvA\u201d si pone l\u2019obiettivo di rispondere a questa sfida, sostenendo progetti di formazione mirati allo sviluppo di competenze in IA. Attenzione particolare ai settori cruciali nel mondo del lavoro. Queste categorie includono l\u2019<strong>agroalimentare, il commercio ed e-commerce, il metalmeccanico, il metalsiderurgico, il mobile e arredo, la moda e abbigliamento e il turismo<\/strong>.<\/p>\n\n\n\n<p>Le azioni formative dovranno essere destinate a <strong>soggetti in condizioni di vulnerabilit\u00e0<\/strong>. Le categorie sono:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>disoccupati<\/li>\n\n\n\n<li>inattivi<\/li>\n\n\n\n<li>NEET<\/li>\n\n\n\n<li>lavoratori a rischio<\/li>\n\n\n\n<li>persone con disabilit\u00e0<\/li>\n\n\n\n<li>minoranze sottorappresentate<\/li>\n\n\n\n<li>vittime di violenza<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La dotazione finanziaria<\/h2>\n\n\n\n<p>Il bando \u201cvIvA\u201d mette a disposizione un <strong>plafond complessivo di 2.600.000 euro<\/strong>. Le proposte progettuali dovranno prevedere un <strong>costo unitario per beneficiario non superiore a 2.000 euro<\/strong> e un <strong>contributo richiesto tra i 200.000 e i 300.000 euro<\/strong>, con una <strong>durata massima di 18 mesi<\/strong>. Le proposte dovranno essere presentate <strong>esclusivamente online tramite la piattaforma Re@dy<\/strong> entro le <strong>ore 13:00 del 12 giugno 2025<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Fondo per la Repubblica Digitale \u2013 Impresa Sociale ha lanciato il bando \u201cvIvA\u201d, volto a promuovere lo sviluppo di competenze digitali nell&#8217;ambito dell\u2019Intelligenza Artificiale (IA) a beneficio di persone in condizioni di vulnerabilit\u00e0. Bando &#8220;vIvA&#8221;: i destinatari Il bando &#8220;vIvA&#8221; \u00e8 destinato ad enti pubblici, privati senza scopo di lucro ed enti del terzo&#8230;<\/p>\n","protected":false},"author":23,"featured_media":45931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[465],"tags":[2008,1094],"class_list":["post-48153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aziende","tag-fondo-repubblica-digitale","tag-intelligenza-artificiale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.5 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bando &quot;vIvA&quot;: opportunit\u00e0 per sviluppare competenze digitali - News Formazione<\/title>\n<meta name=\"description\" content=\"Il Fondo per la Repubblica Digitale \u2013 Impresa Sociale ha lanciato il bando \u201cvIvA\u201d, volto a promuovere lo sviluppo di competenze iA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando &quot;vIvA&quot;: opportunit\u00e0 per sviluppare competenze digitali\" \/>\n<meta property=\"og:description\" content=\"Il Fondo per la Repubblica Digitale \u2013 Impresa Sociale ha lanciato il bando \u201cvIvA\u201d, volto a promuovere lo sviluppo di competenze iA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/\" \/>\n<meta property=\"og:site_name\" content=\"News Formazione\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/timevision\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T08:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2024\/06\/Agevolazioni_per_le_imprese_che_assumono_nel_2024_cosa_cambia_e_cosa_resta_uguale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davide Ferrante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@time_vision\" \/>\n<meta name=\"twitter:site\" content=\"@time_vision\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Ferrante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bando \"vIvA\": opportunit\u00e0 per sviluppare competenze digitali - News Formazione","description":"Il Fondo per la Repubblica Digitale \u2013 Impresa Sociale ha lanciato il bando \u201cvIvA\u201d, volto a promuovere lo sviluppo di competenze iA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/","og_locale":"it_IT","og_type":"article","og_title":"Bando \"vIvA\": opportunit\u00e0 per sviluppare competenze digitali","og_description":"Il Fondo per la Repubblica Digitale \u2013 Impresa Sociale ha lanciato il bando \u201cvIvA\u201d, volto a promuovere lo sviluppo di competenze iA.","og_url":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/","og_site_name":"News Formazione","article_publisher":"https:\/\/www.facebook.com\/timevision","article_published_time":"2025-03-20T08:26:00+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2024\/06\/Agevolazioni_per_le_imprese_che_assumono_nel_2024_cosa_cambia_e_cosa_resta_uguale.png","type":"image\/png"}],"author":"Davide Ferrante","twitter_card":"summary_large_image","twitter_creator":"@time_vision","twitter_site":"@time_vision","twitter_misc":{"Scritto da":"Davide Ferrante","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#article","isPartOf":{"@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/"},"author":{"name":"Davide Ferrante","@id":"https:\/\/www.timevision.it\/news\/#\/schema\/person\/bca81f515796a2febfc11921eab93852"},"headline":"Bando &#8220;vIvA&#8221;: opportunit\u00e0 per sviluppare competenze digitali","datePublished":"2025-03-20T08:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/"},"wordCount":251,"publisher":{"@id":"https:\/\/www.timevision.it\/news\/#organization"},"image":{"@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2024\/06\/Agevolazioni_per_le_imprese_che_assumono_nel_2024_cosa_cambia_e_cosa_resta_uguale.png","keywords":["fondo repubblica digitale","intelligenza artificiale"],"articleSection":["Aziende"],"inLanguage":"it-IT","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.timevision.it\/news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/","url":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/","name":"Bando \"vIvA\": opportunit\u00e0 per sviluppare competenze digitali - News Formazione","isPartOf":{"@id":"https:\/\/www.timevision.it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#primaryimage"},"image":{"@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2024\/06\/Agevolazioni_per_le_imprese_che_assumono_nel_2024_cosa_cambia_e_cosa_resta_uguale.png","datePublished":"2025-03-20T08:26:00+00:00","description":"Il Fondo per la Repubblica Digitale \u2013 Impresa Sociale ha lanciato il bando \u201cvIvA\u201d, volto a promuovere lo sviluppo di competenze iA.","breadcrumb":{"@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#primaryimage","url":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2024\/06\/Agevolazioni_per_le_imprese_che_assumono_nel_2024_cosa_cambia_e_cosa_resta_uguale.png","contentUrl":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2024\/06\/Agevolazioni_per_le_imprese_che_assumono_nel_2024_cosa_cambia_e_cosa_resta_uguale.png","width":1600,"height":900,"caption":"bando \"vIvA\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.timevision.it\/news\/aziende\/bando-viva-opportunita-per-sviluppare-competenze-digitali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.timevision.it\/news\/"},{"@type":"ListItem","position":2,"name":"Bando &#8220;vIvA&#8221;: opportunit\u00e0 per sviluppare competenze digitali"}]},{"@type":"WebSite","@id":"https:\/\/www.timevision.it\/news\/#website","url":"https:\/\/www.timevision.it\/news\/","name":"Timevision","description":"Offrire alle imprese soluzioni ad hoc in materia del lavoro","publisher":{"@id":"https:\/\/www.timevision.it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.timevision.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.timevision.it\/news\/#organization","name":"Timevision scarl","url":"https:\/\/www.timevision.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.timevision.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2020\/11\/logo-timevision-news.png","contentUrl":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2020\/11\/logo-timevision-news.png","width":183,"height":32,"caption":"Timevision scarl"},"image":{"@id":"https:\/\/www.timevision.it\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/timevision","https:\/\/x.com\/time_vision","https:\/\/www.instagram.com\/_timevision_\/","https:\/\/www.linkedin.com\/company\/time-vision","https:\/\/www.youtube.com\/channel\/UC9s4MGbUHcN_HNbhqEiwfLg?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/www.timevision.it\/news\/#\/schema\/person\/bca81f515796a2febfc11921eab93852","name":"Davide Ferrante","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.timevision.it\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e1f5447c1cc548878fa53fbe66fc52d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1f5447c1cc548878fa53fbe66fc52d9?s=96&d=mm&r=g","caption":"Davide Ferrante"},"url":"https:\/\/www.timevision.it\/news\/author\/ferrante\/"}]}},"_links":{"self":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/posts\/48153"}],"collection":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/comments?post=48153"}],"version-history":[{"count":2,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/posts\/48153\/revisions"}],"predecessor-version":[{"id":48155,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/posts\/48153\/revisions\/48155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/media\/45931"}],"wp:attachment":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/media?parent=48153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/categories?post=48153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/tags?post=48153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}