{"id":155,"count":2,"description":"","link":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/","name":"assegno di ricollocazione-tag","slug":"assegno-di-ricollocazione","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.5 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>assegno di ricollocazione-tag Archives - News Formazione<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;Assegno di Ricollocazione con Time Vision: supporto personalizzato per il reinserimento lavorativo, con orientamento professionale e servizi di consulenza per disoccupati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"assegno di ricollocazione-tag Archivi\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;Assegno di Ricollocazione con Time Vision: supporto personalizzato per il reinserimento lavorativo, con orientamento professionale e servizi di consulenza per disoccupati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/\" \/>\n<meta property=\"og:site_name\" content=\"News Formazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@time_vision\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"assegno di ricollocazione-tag Archives - News Formazione","description":"Scopri l'Assegno di Ricollocazione con Time Vision: supporto personalizzato per il reinserimento lavorativo, con orientamento professionale e servizi di consulenza per disoccupati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/","og_locale":"it_IT","og_type":"article","og_title":"assegno di ricollocazione-tag Archivi","og_description":"Scopri l'Assegno di Ricollocazione con Time Vision: supporto personalizzato per il reinserimento lavorativo, con orientamento professionale e servizi di consulenza per disoccupati.","og_url":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/","og_site_name":"News Formazione","twitter_card":"summary_large_image","twitter_site":"@time_vision","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/","url":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/","name":"assegno di ricollocazione-tag Archives - News Formazione","isPartOf":{"@id":"https:\/\/www.timevision.it\/news\/#website"},"description":"Scopri l'Assegno di Ricollocazione con Time Vision: supporto personalizzato per il reinserimento lavorativo, con orientamento professionale e servizi di consulenza per disoccupati.","breadcrumb":{"@id":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.timevision.it\/news\/tag\/assegno-di-ricollocazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.timevision.it\/news\/"},{"@type":"ListItem","position":2,"name":"assegno di ricollocazione-tag"}]},{"@type":"WebSite","@id":"https:\/\/www.timevision.it\/news\/#website","url":"https:\/\/www.timevision.it\/news\/","name":"Timevision","description":"Offrire alle imprese soluzioni ad hoc in materia del lavoro","publisher":{"@id":"https:\/\/www.timevision.it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.timevision.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.timevision.it\/news\/#organization","name":"Timevision scarl","url":"https:\/\/www.timevision.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.timevision.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2020\/11\/logo-timevision-news.png","contentUrl":"https:\/\/www.timevision.it\/news\/wp-content\/uploads\/2020\/11\/logo-timevision-news.png","width":183,"height":32,"caption":"Timevision scarl"},"image":{"@id":"https:\/\/www.timevision.it\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/timevision","https:\/\/x.com\/time_vision","https:\/\/www.instagram.com\/_timevision_\/","https:\/\/www.linkedin.com\/company\/time-vision","https:\/\/www.youtube.com\/channel\/UC9s4MGbUHcN_HNbhqEiwfLg?view_as=subscriber"]}]}},"_links":{"self":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/tags\/155"}],"collection":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.timevision.it\/news\/wp-json\/wp\/v2\/posts?tags=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}